{"id":133829,"date":"2023-07-28T09:31:59","date_gmt":"2023-07-28T09:31:59","guid":{"rendered":"https:\/\/clearchox.com\/de\/?post_type=product&#038;p=133829"},"modified":"2026-06-23T07:40:29","modified_gmt":"2026-06-23T07:40:29","slug":"ocelot-milchschokolade-femme-50-bio","status":"publish","type":"product","link":"https:\/\/clearchox.com\/de\/shop\/ocelot-milchschokolade-femme-50-bio\/","title":{"rendered":"Ocelot &#8211; Milchschokolade Femme 50% BIO"},"content":{"rendered":"<p>Das in Schottland ans\u00e4ssige Unternehmen Ocelot stellt in jeder Hinsicht au\u00dfergew\u00f6hnlich gute Schokolade her. Nicht nur mit wunderbaren Geschmackskombinationen, sondern auch\u00a0in der nachhaltigen und stylischen Verpackung. F\u00fcr den Kakao, genauer gesagt die Schokoladenmasse, arbeiten sie eng mit Original Beans zusammen.<\/p>\n<p>Original Beans hat eine Reihe von Single-Plantage-Schokoladen, die auch die Erhaltung des Regenwaldes f\u00f6rdern. Dieser Virunga wird im <a href=\"https:\/\/de.wikipedia.org\/wiki\/Nationalpark_Virunga\" target=\"_blank\" rel=\"noopener\">Nationalpark Virunga<\/a> im Osten der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Demokratische_Republik_Kongo\" target=\"_blank\" rel=\"noopener\">D.R. Kongo<\/a> geerntet.<\/p>\n<p>Original Beans ist ein idealistischer Schokoladenhersteller. Sie bieten den Kakaobauern ein sog. <em>living income<\/em> und zahlen sogar fast das Doppelte der Fairtrade-Pr\u00e4mie extra. Aber sie tun noch mehr: Sie helfen bei der Anpflanzung von B\u00e4umen, um den Wald wiederherzustellen, unterrichten die Bauern in der besten Verarbeitung von Kakaobohnen und unterhalten selbstverst\u00e4ndlich auch eine Baumschule f\u00fcr Kakaob\u00e4ume.<\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Vertaling\"><span class=\"Y2IQFc\" lang=\"en\"><strong>Zutaten:<\/strong> Kakaomasse Original Beans Couverture Femmes de Virunga, Kakaobutter, Rohrohrzucker, Voll<span style=\"color: #993300;\"><strong><em>milch<\/em><\/strong><\/span>pulver<br \/>\n<\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Vertaling\"><span class=\"Y2IQFc\" lang=\"en\"><strong>Geschmacksnoten: <\/strong>eine Tasse Cappuccino und ger\u00f6stete N\u00fcsse, gepaart mit feinen Noten\u00a0von Schattenmorellen und schwarzem Tee des Amelonado Kakaos<\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Vertaling\"><span style=\"color: #993300;\"><em><strong><span class=\"Y2IQFc\" lang=\"en\">Enth\u00e4lt Milch. Hergestellt in einer Manufaktur, die auch Gluten und N\u00fcsse verarbeitet.<\/span><\/strong><\/em><\/span><\/p>\n<table width=\"593\">\n<tbody>\n<tr>\n<td width=\"333\"><strong>Nutritional values\/Voedingswaarde\/N\u00e4hrwerte\/Valeurs nutritionnelles<br \/>\n<\/strong><\/td>\n<td width=\"260\"><strong>per\/pro\/pour 100 g<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Energy\/Energie\/Valeur \u00e9nerg\u00e9tique<\/td>\n<td>570 kCal \/ 2373 kJ<\/td>\n<\/tr>\n<tr>\n<td>Fat\/Vet\/Fett\/Lipides<\/td>\n<td>39 g<\/td>\n<\/tr>\n<tr>\n<td>of which saturated\/waarvan verzadigd\/davon ges\u00e4ttigte Fetts\u00e4uren\/dont acides gras satur\u00e9s<\/td>\n<td>25 g<\/td>\n<\/tr>\n<tr>\n<td>Carbohydrates\/Koolhydraten\/Kohlenhydrate\/Glucides<\/td>\n<td>43 g<\/td>\n<\/tr>\n<tr>\n<td>davon Zucker\/waarvan suiker\/of which sugar\/dont sucre<\/td>\n<td>40 g<\/td>\n<\/tr>\n<tr>\n<td>Nahrungsfasern\/voedingsvezels\/dietary fibres\/des fibres alimentaires<\/td>\n<td>6 g<\/td>\n<\/tr>\n<tr>\n<td>Protein\/Eiwit\/Eiweiss\/Prot\u00e9ine<\/td>\n<td>8 g<\/td>\n<\/tr>\n<tr>\n<td>Salt\/Zout\/Salz\/Sel<\/td>\n<td>0 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>EAN 0634158969157<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine au\u00dfergew\u00f6hnliche dunkle Bio-Milchschokolade aus seltenen Amelonado-Kakaobohnen, die von einer bahnbrechenden Frauenkooperative im Ostkongo angebaut werden, und der reichhaltigen Milch von Schweizer Braunviehk\u00fchen, die in kleinen Herden auf saftigen Bergweiden grasen.<\/p>\n","protected":false},"featured_media":133809,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1134],"product_cat":[735,15],"product_tag":[],"class_list":["post-133829","product","type-product","status-publish","has-post-thumbnail","product_brand-ocelot","product_cat-bio","product_cat-schokolade","product_shipping_class-16","infinite-scroll-item","resize-featured-image","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","wc-has-gallery","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/product\/133829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/comments?post=133829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/media\/133809"}],"wp:attachment":[{"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/media?parent=133829"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/product_brand?post=133829"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/product_cat?post=133829"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/clearchox.com\/de\/wp-json\/wp\/v2\/product_tag?post=133829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}